{"id":40442,"date":"2026-07-13T16:10:19","date_gmt":"2026-07-13T15:10:19","guid":{"rendered":"https:\/\/www.galeriedowntown.com\/pieces\/%designers%\/horizon-watcher\/"},"modified":"2026-07-15T11:39:57","modified_gmt":"2026-07-15T10:39:57","slug":"horizon-watcher","status":"publish","type":"pieces","link":"https:\/\/www.galeriedowntown.com\/en\/pieces\/richard-texier\/horizon-watcher\/","title":{"rendered":"Horizon watcher"},"content":{"rendered":"","protected":false},"featured_media":40441,"template":"","designers":[194],"type_mobilier":[212],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Horizon watcher - Laffanour | Galerie Downtown<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.galeriedowntown.com\/en\/pieces\/richard-texier\/horizon-watcher\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Horizon watcher - Laffanour | Galerie Downtown\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.galeriedowntown.com\/en\/pieces\/richard-texier\/horizon-watcher\/\" \/>\n<meta property=\"og:site_name\" content=\"Laffanour | Galerie Downtown\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T10:39:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.galeriedowntown.com\/wp-content\/uploads\/2026\/07\/Capture-decran-2026-07-13-a-16.png\" \/>\n\t<meta property=\"og:image:width\" content=\"949\" \/>\n\t<meta property=\"og:image:height\" content=\"949\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.galeriedowntown.com\/en\/pieces\/richard-texier\/horizon-watcher\/\",\"url\":\"https:\/\/www.galeriedowntown.com\/en\/pieces\/richard-texier\/horizon-watcher\/\",\"name\":\"Horizon watcher - Laffanour | Galerie Downtown\",\"isPartOf\":{\"@id\":\"https:\/\/www.galeriedowntown.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.galeriedowntown.com\/en\/pieces\/richard-texier\/horizon-watcher\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.galeriedowntown.com\/en\/pieces\/richard-texier\/horizon-watcher\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.galeriedowntown.com\/wp-content\/uploads\/2026\/07\/Capture-decran-2026-07-13-a-16.png\",\"datePublished\":\"2026-07-13T15:10:19+00:00\",\"dateModified\":\"2026-07-15T10:39:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.galeriedowntown.com\/en\/pieces\/richard-texier\/horizon-watcher\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.galeriedowntown.com\/en\/pieces\/richard-texier\/horizon-watcher\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.galeriedowntown.com\/en\/pieces\/richard-texier\/horizon-watcher\/#primaryimage\",\"url\":\"https:\/\/www.galeriedowntown.com\/wp-content\/uploads\/2026\/07\/Capture-decran-2026-07-13-a-16.png\",\"contentUrl\":\"https:\/\/www.galeriedowntown.com\/wp-content\/uploads\/2026\/07\/Capture-decran-2026-07-13-a-16.png\",\"width\":949,\"height\":949},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.galeriedowntown.com\/en\/pieces\/richard-texier\/horizon-watcher\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Mobilier\",\"item\":\"https:\/\/www.galeriedowntown.com\/en\/pieces\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Horizon watcher\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.galeriedowntown.com\/en\/#website\",\"url\":\"https:\/\/www.galeriedowntown.com\/en\/\",\"name\":\"Laffanour | Galerie Downtown\",\"description\":\"Laffanour | Galerie Downtown\",\"publisher\":{\"@id\":\"https:\/\/www.galeriedowntown.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.galeriedowntown.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.galeriedowntown.com\/en\/#organization\",\"name\":\"Laffanour | Galerie Downtown\",\"url\":\"https:\/\/www.galeriedowntown.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.galeriedowntown.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.galeriedowntown.com\/wp-content\/uploads\/2021\/05\/Laffanour-Large-RVB-copie.jpg\",\"contentUrl\":\"https:\/\/www.galeriedowntown.com\/wp-content\/uploads\/2021\/05\/Laffanour-Large-RVB-copie.jpg\",\"width\":581,\"height\":280,\"caption\":\"Laffanour | Galerie Downtown\"},\"image\":{\"@id\":\"https:\/\/www.galeriedowntown.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Horizon watcher - Laffanour | Galerie Downtown","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.galeriedowntown.com\/en\/pieces\/richard-texier\/horizon-watcher\/","og_locale":"en_US","og_type":"article","og_title":"Horizon watcher - Laffanour | Galerie Downtown","og_url":"https:\/\/www.galeriedowntown.com\/en\/pieces\/richard-texier\/horizon-watcher\/","og_site_name":"Laffanour | Galerie Downtown","article_modified_time":"2026-07-15T10:39:57+00:00","og_image":[{"width":949,"height":949,"url":"https:\/\/www.galeriedowntown.com\/wp-content\/uploads\/2026\/07\/Capture-decran-2026-07-13-a-16.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.galeriedowntown.com\/en\/pieces\/richard-texier\/horizon-watcher\/","url":"https:\/\/www.galeriedowntown.com\/en\/pieces\/richard-texier\/horizon-watcher\/","name":"Horizon watcher - Laffanour | Galerie Downtown","isPartOf":{"@id":"https:\/\/www.galeriedowntown.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.galeriedowntown.com\/en\/pieces\/richard-texier\/horizon-watcher\/#primaryimage"},"image":{"@id":"https:\/\/www.galeriedowntown.com\/en\/pieces\/richard-texier\/horizon-watcher\/#primaryimage"},"thumbnailUrl":"https:\/\/www.galeriedowntown.com\/wp-content\/uploads\/2026\/07\/Capture-decran-2026-07-13-a-16.png","datePublished":"2026-07-13T15:10:19+00:00","dateModified":"2026-07-15T10:39:57+00:00","breadcrumb":{"@id":"https:\/\/www.galeriedowntown.com\/en\/pieces\/richard-texier\/horizon-watcher\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.galeriedowntown.com\/en\/pieces\/richard-texier\/horizon-watcher\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.galeriedowntown.com\/en\/pieces\/richard-texier\/horizon-watcher\/#primaryimage","url":"https:\/\/www.galeriedowntown.com\/wp-content\/uploads\/2026\/07\/Capture-decran-2026-07-13-a-16.png","contentUrl":"https:\/\/www.galeriedowntown.com\/wp-content\/uploads\/2026\/07\/Capture-decran-2026-07-13-a-16.png","width":949,"height":949},{"@type":"BreadcrumbList","@id":"https:\/\/www.galeriedowntown.com\/en\/pieces\/richard-texier\/horizon-watcher\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Mobilier","item":"https:\/\/www.galeriedowntown.com\/en\/pieces\/"},{"@type":"ListItem","position":2,"name":"Horizon watcher"}]},{"@type":"WebSite","@id":"https:\/\/www.galeriedowntown.com\/en\/#website","url":"https:\/\/www.galeriedowntown.com\/en\/","name":"Laffanour | Galerie Downtown","description":"Laffanour | Galerie Downtown","publisher":{"@id":"https:\/\/www.galeriedowntown.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.galeriedowntown.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.galeriedowntown.com\/en\/#organization","name":"Laffanour | Galerie Downtown","url":"https:\/\/www.galeriedowntown.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.galeriedowntown.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.galeriedowntown.com\/wp-content\/uploads\/2021\/05\/Laffanour-Large-RVB-copie.jpg","contentUrl":"https:\/\/www.galeriedowntown.com\/wp-content\/uploads\/2021\/05\/Laffanour-Large-RVB-copie.jpg","width":581,"height":280,"caption":"Laffanour | Galerie Downtown"},"image":{"@id":"https:\/\/www.galeriedowntown.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.galeriedowntown.com\/en\/wp-json\/wp\/v2\/pieces\/40442"}],"collection":[{"href":"https:\/\/www.galeriedowntown.com\/en\/wp-json\/wp\/v2\/pieces"}],"about":[{"href":"https:\/\/www.galeriedowntown.com\/en\/wp-json\/wp\/v2\/types\/pieces"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.galeriedowntown.com\/en\/wp-json\/wp\/v2\/media\/40441"}],"wp:attachment":[{"href":"https:\/\/www.galeriedowntown.com\/en\/wp-json\/wp\/v2\/media?parent=40442"}],"wp:term":[{"taxonomy":"designers","embeddable":true,"href":"https:\/\/www.galeriedowntown.com\/en\/wp-json\/wp\/v2\/designers?post=40442"},{"taxonomy":"type_mobilier","embeddable":true,"href":"https:\/\/www.galeriedowntown.com\/en\/wp-json\/wp\/v2\/type_mobilier?post=40442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}